{"id":19531,"date":"2022-01-05T12:31:14","date_gmt":"2022-01-05T15:31:14","guid":{"rendered":"http:\/\/www.primeranota.cl\/web\/?p=19531"},"modified":"2022-01-05T12:31:14","modified_gmt":"2022-01-05T15:31:14","slug":"francisco-huenchumilla-a-proposito-del-dialogo-con-la-cam","status":"publish","type":"post","link":"http:\/\/www.primeranota.cl\/web\/region\/francisco-huenchumilla-a-proposito-del-dialogo-con-la-cam\/","title":{"rendered":"Francisco Huenchumilla: \u201cA prop\u00f3sito del di\u00e1logo con la CAM\u201d"},"content":{"rendered":"<p>A prop\u00f3sito de las declaraciones de Iskia Siches y Giorgio Jackson sobre la voluntad de di\u00e1logo del nuevo gobierno respecto del conflicto del estado con el pueblo mapuche, han surgido variadas voces opinando sobre el particular, cometiendo, quiero creer que involuntariamente, algunos equ\u00edvocos sobre los cuales estimo necesario dar mi opini\u00f3n.<\/p>\n<p>No se trata, naturalmente, del di\u00e1logo como un concepto te\u00f3rico propio de la pol\u00edtica en democracia o de los seres humanos con nuestros semejantes, con lo cual todos vamos a estar de acuerdo. Se trata del di\u00e1logo como un m\u00e9todo para abordar un problema, en este caso pol\u00edtico, que la autoridad pretende resolver, por ser real, concreto y grave. El problema de la macrozona sur, como se le ha dado en llamarlo ahora, re\u00fane esas caracter\u00edsticas desde hace m\u00e1s de 20 a\u00f1os, 24 para ser m\u00e1s exactos, en su dimensi\u00f3n de la violencia como la conocemos. Ning\u00fan gobierno desde el a\u00f1o 1997 ha dado con la soluci\u00f3n; m\u00e1s a\u00fan, aplicaron recetas equivocadas sin destino. Y esto ha sucedido simplemente porque los gobiernos no han dado respuesta a los temas de fondo que demanda el pueblo mapuche<strong>: reconocimiento y reparaci\u00f3n.<\/strong><\/p>\n<p><strong>El reconocimiento <\/strong>dice relaci\u00f3n con los derechos pol\u00edticos tales como el reconocimiento constitucional (que tod@s los candidatos presidenciales prometen en sus programas, pero que llegados al poder no se concreta); la plurinacionalidad, la autonom\u00eda, esca\u00f1os reservados, derechos colectivos, todos los cuales se encuentran vigentes en distintos instrumentos del Derecho Internacional de los Pueblos Ind\u00edgenas, y que el estado de Chile ha firmado y est\u00e1n en plena pr\u00e1ctica, adem\u00e1s, en los pa\u00edses desarrollados que han solucionado, por la v\u00eda del di\u00e1logo, su relaci\u00f3n con los pueblos originarios y tambi\u00e9n con procesos no exentos de violencia.<\/p>\n<p>Este problema &#8211;<strong>el reconocimiento- <\/strong>para alivio del gobierno de Gabriel Boric lo va a resolver la Convenci\u00f3n Constitucional y, de esa manera, habremos avanzado como pa\u00eds en esta materia que en 30 a\u00f1os no pudimos, o no quisimos avanzar.<\/p>\n<p><strong>La reparaci\u00f3n <\/strong>dice relaci\u00f3n con la respuesta pendiente del estado de Chile acerca de la devoluci\u00f3n de las tierras que usurp\u00f3 en el siglo 19, y cuyo lento y engorroso proceso se ha arrastrado, sin soluci\u00f3n definitiva y cierta, desde el nacimiento de la Conadi con la dictaci\u00f3n de la ley ind\u00edgena el a\u00f1o 1993. Aqu\u00ed la respuesta no la tiene la CAM. La tienen las forestales, los gremios de los agricultores y el gobierno. Porque de lo que se trata es determinar y dar respuesta a la pregunta sobre \u201ccu\u00e1ndo hablamos de tierras de qu\u00e9 estamos hablando\u201d; como en el concurso, \u00bfrespuesta definitiva? S\u00ed, respuesta definitiva. Comprendo que encontrar la respuesta no es f\u00e1cil. Pero, de eso se trata la pol\u00edtica, de resolver los problemas que aquejan al pa\u00eds. Y su car\u00e1cter debe ser definitivo para que todos los actores tengan certeza respecto de los escenarios futuros en los cuales desenvolver\u00e1n sus vidas.<\/p>\n<p>Quiero entender que, en ese escenario, los dirigentes del gobierno que asume en marzo pretenden dialogar con todos actores, mapuche y no mapuche, algunos tan importantes como los gremios empresariales; y el diverso pueblo mapuche, con los distintos liderazgos y centros de poder que lo caracterizan, incluida la CAM, cuya importancia radica -no en validar la violencia como m\u00e9todo al dialogar con ella- sino para saber con certeza en qu\u00e9 circunstancias y bajo qu\u00e9 condiciones est\u00e1 dispuesta a deponer ese camino, incompatible con la democracia, para que el gobierno tenga un completo panorama del escenario en que tendr\u00e1 que afrontar el proceso de <strong>reparaci\u00f3n<\/strong> y adoptar, en consecuencia, los objetivos estrat\u00e9gicos pertinentes compatibles con el estado de derecho.<\/p>\n<p>De m\u00e1s est\u00e1 decir, pero lo digo por si alguien tuviera dudas, que la interpelaci\u00f3n por la <strong>reparaci\u00f3n <\/strong>la comparte la totalidad del pueblo mapuche. La diferencia est\u00e1 en el m\u00e9todo de la violencia que la mayor\u00eda sustancial rechaza. Por lo tanto, la respuesta a la petici\u00f3n de <strong>reparaci\u00f3n<\/strong> debe ser univoca y definitiva. No hay dos voces al respecto.<\/p>\n<p>Debo entender, entonces, que el di\u00e1logo con la CAM se explica porque siendo uno m\u00e1s de los distintos centros de poder del pueblo mapuche, tiene una caracter\u00edstica singular que es su reivindicaci\u00f3n de la violencia como m\u00e9todo de lucha, y por ello se hace necesario neutralizarla mediante una completa pol\u00edtica de <strong>reparaci\u00f3n <\/strong>que, aceptada por ella, permitir\u00eda terminar con la violencia sin necesidad de, como \u00faltima ratio, recurrir a la acci\u00f3n de la fuerza del estado. No se trata, por lo tanto, de una negociaci\u00f3n entre pares y con ello producir una legitimaci\u00f3n; se trata simplemente de una estrategia para dimensionar los t\u00e9rminos de la <strong>reparaci\u00f3n, <\/strong>de manera tal que \u00e9sta sea de verdad, y de esa manera, posibilitar la soluci\u00f3n del conflicto, terminando con la violencia y alcanzando la paz regional como un bien superior; sintiendo todas las partes que la soluci\u00f3n es justa y leg\u00edtima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prop\u00f3sito de las declaraciones de Iskia Siches y Giorgio Jackson sobre la voluntad de di\u00e1logo del nuevo gobierno respecto del conflicto del estado con&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7152,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267,3],"tags":[],"_links":{"self":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/19531"}],"collection":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=19531"}],"version-history":[{"count":1,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/19531\/revisions"}],"predecessor-version":[{"id":19532,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/19531\/revisions\/19532"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/7152"}],"wp:attachment":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=19531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=19531"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=19531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}