{"id":4455,"date":"2018-12-10T08:11:49","date_gmt":"2018-12-10T11:11:49","guid":{"rendered":"http:\/\/www.primeranota.cl\/web\/?p=4455"},"modified":"2018-12-10T08:11:49","modified_gmt":"2018-12-10T11:11:49","slug":"caso-catrillanca-la-semana-del-ministro-chadwick","status":"publish","type":"post","link":"http:\/\/www.primeranota.cl\/web\/portada\/caso-catrillanca-la-semana-del-ministro-chadwick\/","title":{"rendered":"Caso Catrillanca: La Semana del Ministro Chadwick"},"content":{"rendered":"<p>El ministro del Interior y Seguridad P\u00fablica, Andr\u00e9s Chadwick, enfrentar\u00e1 una tensa semana en el Congreso tras la muerte del comunero mapuche Camilo Catrillanca, ocurrida el pasado 14 de noviembre al interior de Temucuicui en medio de un operativo de Carabineros. Esto porque ma\u00f1ana desde las 16:00 horas ser\u00e1 interpelado por la diputada de origen mapuche y representante de La Araucan\u00eda, Emilia Nuyado (PS), tras una acci\u00f3n impulsada por la oposici\u00f3n.<\/p>\n<p>En el cuestionario y seg\u00fan ha revelado la propia parlamentaria, se incorporar\u00e1n preguntas relacionadas a todas las dimensiones que mantienen a la zona en conflicto y para eso ella se ha preparado visitando distintas comunidades y a dirigentes encarcelados. Adem\u00e1s anunci\u00f3, que tal como se hab\u00eda rumoreado, saludar\u00e1 al secretario de Estado en mapungun. &#8220;Quiero abordar temas que no han sido visibles y que puedan ser escuchados&#8221;, Nuyado en Emol TV resaltando que el interrogatorio no solo se centrar\u00e1 en el caso Catrillanca y al accionar del denominado &#8220;Comando Jungla&#8221; en la regi\u00f3n.<\/p>\n<p>Respuestas al Senado Al d\u00eda siguiente el ministro deber\u00e1 estar, a las 11:00 horas, frente al pleno del Senado en donde se realizar\u00e1 una sesi\u00f3n especial para abordar el mismo tema. En la ocasi\u00f3n, Chadwick estar\u00e1 acompa\u00f1ado, ya que tambi\u00e9n fue citado por el Congreso, por el intendente de La Araucan\u00eda, Jorge Atton.<\/p>\n<p>La sesi\u00f3n, solicitada por los senadores liderados por Francisco Huenchumilla (DC) y Jaime Quintana (PPD), hab\u00eda sido inicialmente convocada para el pasado 28 de noviembre, sin embargo, debi\u00f3 ser reprogramada para este mi\u00e9rcoles luego de que el ministro del Interior sufriera una ca\u00edda al interior del Palacio de La Moneda. Seg\u00fan explic\u00f3 el presidente del Senado, Carlos Montes (PS), lo que buscan con este encuentro es &#8220;es poder dialogar con el ministro y conocer todo lo que ocurri\u00f3 en La Araucan\u00eda, los fundamentos en sus dichos, las acciones que se tomaron previo a la operaci\u00f3n del Comando Jungla y a su vez c\u00f3mo esto tuvo implicancias en la estrategia territorial que ten\u00eda carabineros y el efecto que tuvo la muerte del comunero&#8221;. As\u00ed como tambi\u00e9n, seg\u00fan dijo, apuntan a poder &#8220;profundizar&#8221; en los antecedentes que rodean la muerte de Catrillanca &#8220;y a su vez en la estrategia futura; qu\u00e9 se quiere hacer para asumir la experiencia, los errores que se han cometido y proyectar una pol\u00edtica social, cultural junto a un despliegue de las fuerzas policiales que sea m\u00e1s compatible con la vida normal de esas comunidades&#8221;.<\/p>\n<p>Operaci\u00f3n Hurac\u00e1n Otro asunto que se revisar\u00e1 en el Congreso ser\u00e1 el informe de la comisi\u00f3n investigadora sobre la operaci\u00f3n Hurac\u00e1n. Caso en que se investiga la manipulaci\u00f3n de evidencia que permiti\u00f3 formalizar a ocho comuneros mapuche, hoy sobrese\u00eddos, por la quema de 58 camiones en La Araucan\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: Emol.com<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro del Interior y Seguridad P\u00fablica, Andr\u00e9s Chadwick, enfrentar\u00e1 una tensa semana en el Congreso tras la muerte del comunero mapuche Camilo Catrillanca, ocurrida&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"_links":{"self":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/4455"}],"collection":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=4455"}],"version-history":[{"count":1,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/4455\/revisions"}],"predecessor-version":[{"id":4456,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/4455\/revisions\/4456"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/3944"}],"wp:attachment":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=4455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=4455"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=4455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}