{"id":6564,"date":"2019-03-24T08:46:02","date_gmt":"2019-03-24T11:46:02","guid":{"rendered":"http:\/\/www.primeranota.cl\/web\/?p=6564"},"modified":"2019-03-24T08:46:02","modified_gmt":"2019-03-24T11:46:02","slug":"frei-por-criticas-a-bolsonaro-cuantas-veces-recibimos-a-fidel-castro-y-hugo-chavez","status":"publish","type":"post","link":"http:\/\/www.primeranota.cl\/web\/pais\/frei-por-criticas-a-bolsonaro-cuantas-veces-recibimos-a-fidel-castro-y-hugo-chavez\/","title":{"rendered":"Frei por cr\u00edticas a Bolsonaro: &#8220;\u00bfCu\u00e1ntas veces recibimos a Fidel Castro y Hugo Ch\u00e1vez?&#8221;"},"content":{"rendered":"<p>No fueron pocos los pol\u00edticos de la oposici\u00f3n que criticaron la visita de Jair Bolsonaro, quien en las \u00faltimas horas estuvo en Chile por la cumbre Prosur.<br \/>\nSin embargo, hubo quienes s\u00ed se reunieron como el Jefe de Estado de Brasil, como fue el caso del ex Presidente Eduardo Frei Ruiz-Tagle.<br \/>\n&#8220;\u00bfCu\u00e1ntas veces, en la cumbre iberoamericana de 1998, estuvo Fidel Castro en La Moneda. \u00bfCu\u00e1ntas veces estuvimos con Hugo Ch\u00e1vez? Seg\u00fan esos criterios, nunca los pudimos haber recibido&#8221;, manifest\u00f3.<br \/>\nAdem\u00e1s, el hijo del fallecido ex Mandatario Eduardo Frei Montalva justific\u00f3 su presencia. &#8220;Cumplo con mi deber, como ex Presidente, de relacionarme con pol\u00edticas de Estado y con los l\u00edderes de otros pa\u00edses. Cada uno responde por sus dichos y actos&#8221;, se\u00f1al\u00f3.<br \/>\nADN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No fueron pocos los pol\u00edticos de la oposici\u00f3n que criticaron la visita de Jair Bolsonaro, quien en las \u00faltimas horas estuvo en Chile por la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,267],"tags":[],"_links":{"self":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/6564"}],"collection":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=6564"}],"version-history":[{"count":1,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/6564\/revisions"}],"predecessor-version":[{"id":6565,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/6564\/revisions\/6565"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/3241"}],"wp:attachment":[{"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=6564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=6564"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=6564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}