{"id":13137,"date":"2020-04-15T08:41:28","date_gmt":"2020-04-15T12:41:28","guid":{"rendered":"http:\/\/www.primeranota.cl\/web\/?p=13137"},"modified":"2020-04-15T08:41:28","modified_gmt":"2020-04-15T12:41:28","slug":"andrea-repetto-por-plan-economico-para-las-pymes-los-bancos-estan-haciendo-esto-porque-es-un-negocio","status":"publish","type":"post","link":"https:\/\/www.primeranota.cl\/web\/pais\/andrea-repetto-por-plan-economico-para-las-pymes-los-bancos-estan-haciendo-esto-porque-es-un-negocio\/","title":{"rendered":"Andrea Repetto por plan econ\u00f3mico para las pymes: \u201cLos bancos est\u00e1n haciendo esto porque es un negocio\u201d"},"content":{"rendered":"<p>La economista de la Universidad Adolfo Ib\u00e1\u00f1ez,\u00a0<strong>Andrea Repetto<\/strong>, convers\u00f3 esta ma\u00f1ana con\u00a0<em>CHV Noticias AM<\/em>\u00a0y se refiri\u00f3 al\u00a0<a href=\"https:\/\/www.cnnchile.com\/economia\/pinera-plan-economico-emergencia-creditos-empresas_20200412\/\">programa anunciado por el presidente Sebasti\u00e1n Pi\u00f1era<\/a>.<\/p>\n<p>Repetto profundiz\u00f3 en uno de los puntos del plan econ\u00f3mico, que hace referencia al<strong>\u00a0financiamiento que entregar\u00e1n los bancos a las micro, peque\u00f1as y medianas empresas.\u00a0<\/strong><\/p>\n<p>\u201c<b>Los bancos van a ganar plata. No hay que ser ingenuos. Los bancos est\u00e1n haciendo esto porque es un negocio\u201d<\/b>, asegur\u00f3.<\/p>\n<div><\/div>\n<p>Por lo anterior, enfatiz\u00f3 que\u00a0<strong>se tratar\u00eda de un negocio \u201cporque en el fondo el Estado le est\u00e1 cubriendo mucho de sus costos. Le est\u00e1 entregando una garant\u00eda hasta el 85%\u201d<\/strong>.<\/p>\n<p>\u201cSi los due\u00f1os de las pymes no pagan, entonces una parte importante la van a recibir igual, porque el Estado la va a pagar\u201d, agreg\u00f3.<\/p>\n<div>\n<div class=\"the-banner\">\u201c\u00bfQu\u00e9 es lo que le queda al banco? Le quedan los costos operacionales, que tienen que pagarlo, evaluar a los clientes, definir a qui\u00e9nes les van e entregar y una utilidad. <strong>Yo creo que en esa brecha va a haber una utilidad y no me extra\u00f1ar\u00eda que se pegaran al 3,5% nominal<\/strong>\u201d, enfatiz\u00f3.<\/div>\n<\/div>\n<p>De acuerdo a los lineamientos entregados por el Ejecutivo, los montos de la anunciada<strong>\u00a0l\u00ednea de Cr\u00e9dito COVID-19<\/strong>\u00a0<strong>para capital de trabajo podr\u00e1n llegar hasta el equivalente a 3 meses de ventas de la empresa<\/strong>, en un periodo normal (octubre 2018 \u2013 septiembre 2019).<\/p>\n<p>Adem\u00e1s, ratificaron que<strong>\u00a0tendr\u00e1 6 meses de gracia<\/strong>\u00a0y ser\u00e1 pagadera en cuotas durante un periodo de entre 24 y 48 meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La economista de la Universidad Adolfo Ib\u00e1\u00f1ez,\u00a0Andrea Repetto, convers\u00f3 esta ma\u00f1ana con\u00a0CHV Noticias AM\u00a0y se refiri\u00f3 al\u00a0programa anunciado por el presidente Sebasti\u00e1n Pi\u00f1era. Repetto profundiz\u00f3&#8230;<\/p>\n","protected":false},"author":2,"featured_media":13138,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","wpai_meta_description":"","footnotes":""},"categories":[4,267],"tags":[],"class_list":["post-13137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pais","category-portada"],"_links":{"self":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/13137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=13137"}],"version-history":[{"count":1,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/13137\/revisions"}],"predecessor-version":[{"id":13139,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/13137\/revisions\/13139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/13138"}],"wp:attachment":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=13137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=13137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=13137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}