{"id":14256,"date":"2020-06-15T14:18:44","date_gmt":"2020-06-15T18:18:44","guid":{"rendered":"http:\/\/www.primeranota.cl\/web\/?p=14256"},"modified":"2020-06-15T14:18:44","modified_gmt":"2020-06-15T18:18:44","slug":"indignantes-despidos-de-profesionales-de-el-diario-austral-de-la-araucania","status":"publish","type":"post","link":"https:\/\/www.primeranota.cl\/web\/region\/indignantes-despidos-de-profesionales-de-el-diario-austral-de-la-araucania\/","title":{"rendered":"Indignantes despidos de profesionales de El Diario Austral de La Araucan\u00eda"},"content":{"rendered":"<p>Con sorpresa, tristeza y profunda indignaci\u00f3n, nos hemos informado que con fecha, viernes 12 de junio, cinco profesionales periodistas fueron despedidos de El Diario Austral de La Araucan\u00eda.<\/p>\n<p>Como Colegio de Periodistas, Regional Araucan\u00eda, lamentamos y rechazamos esta medida, a todas luces descabellada, centralista y economicista, aplicada desde la administraci\u00f3n de medios regionales de El Mercurio y que tambi\u00e9n afecta a trabajadores y trabajadoras de la comunicaci\u00f3n desde Arica a Puerto Montt, con alrededor de 60 personas que, de un d\u00eda para otro, quedaron sin su fuente laboral.<\/p>\n<p>Estas decisiones, adoptadas en el peor momento de la pandemia por Covid-19, pudieron solucionarse de otra forma, usando instancias como la protecci\u00f3n del empleo, o realizar acuerdos con los trabajadores, en un acto de respeto laboral con quienes hacen periodismo en terreno. Sin embargo, han optado por materializar a personas, transform\u00e1ndolas solo en n\u00fameros rojos y que hab\u00eda que sacar para volver a los c\u00e1lculos azules, con un nivel de frialdad incomprensible.<\/p>\n<p>No se ha considerado ni valorado la trayectoria profesional de los colegas despedidos; ning\u00fan reconocimiento a su aporte al periodismo regional y, en especial, a la situaci\u00f3n que vivimos en la actualidad, que ha significado que muchos de nuestros colegas se expongan d\u00eda a d\u00eda para cumplir con su labor de informar a la sociedad, a la cual nos debemos.<\/p>\n<p>Estos periodistas que hoy llegan a su casa sin trabajo, se suman a los miles de hombres y mujeres en todas las regiones que ya no tienen como llevar recursos a sus hogares; m\u00e1s a\u00fan, en un momento en que muchas empresas se han aprovechado de lo que ocurre para rebajar gastos a costa de su capital humano. Y no debemos olvidar que detr\u00e1s de cada despedido\/a hay una familia e hijos\/as, que tambi\u00e9n sufrir\u00e1n las consecuencias, algo que, por cierto, tampoco se toma en cuenta al momento de decidir.<\/p>\n<p>En medio de tanto rumor e informaci\u00f3n falsa o confusa, incluso emanada de fuentes oficiales; y cuando m\u00e1s periodismo robusto y confiable necesitamos, estas decisiones absolutamente nefastas vienen a confirmar que, m\u00e1s que la b\u00fasqueda por informar con veracidad, entretener y educar, importan los ingresos, los n\u00fameros, tomando de seguro estas decisiones desde la capital, detr\u00e1s de una pantalla y un escritorio.<\/p>\n<p>Finalmente, queremos solidarizar, con todos los y las colegas despedidos\/as, a quienes ya contactamos en su gran mayor\u00eda, y exigimos a quienes toman estas decisiones que abran sus ojos y vean que est\u00e1n matando de manera brutal la prensa regional.<\/p>\n<p>&nbsp;<\/p>\n<p>CONSEJO REGIONAL ARAUCAN\u00cdA<\/p>\n<p>COLEGIO DE PERIODISTAS DE CHILE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con sorpresa, tristeza y profunda indignaci\u00f3n, nos hemos informado que con fecha, viernes 12 de junio, cinco profesionales periodistas fueron despedidos de El Diario Austral&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14257,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","wpai_meta_description":"","footnotes":""},"categories":[267,3],"tags":[],"class_list":["post-14256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","category-region"],"_links":{"self":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/14256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=14256"}],"version-history":[{"count":1,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/14256\/revisions"}],"predecessor-version":[{"id":14258,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/14256\/revisions\/14258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/14257"}],"wp:attachment":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=14256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=14256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=14256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}