{"id":20843,"date":"2026-07-14T19:17:48","date_gmt":"2026-07-14T23:17:48","guid":{"rendered":"https:\/\/www.primeranota.cl\/web\/?p=20843"},"modified":"2026-07-14T19:17:48","modified_gmt":"2026-07-14T23:17:48","slug":"la-confianza-economica-de-los-chilenos-cae-a-su-peor-nivel-en-12-anos","status":"publish","type":"post","link":"https:\/\/www.primeranota.cl\/web\/region\/la-confianza-economica-de-los-chilenos-cae-a-su-peor-nivel-en-12-anos\/","title":{"rendered":"La confianza economica de los chilenos cae a su peor nivel en 12 a\u00f1os"},"content":{"rendered":"<p>La mala percepci\u00f3n econ\u00f3mica de los chilenos toc\u00f3 esta semana un punto que no se ve\u00eda desde hace m\u00e1s de una d\u00e9cada: el 56% de los encuestados calific\u00f3 negativamente la situaci\u00f3n econ\u00f3mica personal y familiar, el nivel m\u00e1s alto desde marzo de 2014, seg\u00fan la encuesta publicada este domingo por Cadem. El progresivo pesimismo de los ciudadanos respecto a su bolsillo llega cuando el Gobierno de Jos\u00e9 Antonio Kast enfrenta un desgaste sostenido en su aprobaci\u00f3n \u2014que seg\u00fan Criteria lleg\u00f3 esta semana a su nivel m\u00e1s bajo desde que asumi\u00f3 el 11 de marzo\u2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mala percepci\u00f3n econ\u00f3mica de los chilenos toc\u00f3 esta semana un punto que no se ve\u00eda desde hace m\u00e1s de una d\u00e9cada: el 56% de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":19761,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","wpai_meta_description":"","footnotes":""},"categories":[267,3],"tags":[],"class_list":["post-20843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","category-region"],"_links":{"self":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/20843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=20843"}],"version-history":[{"count":1,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/20843\/revisions"}],"predecessor-version":[{"id":20844,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/20843\/revisions\/20844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/19761"}],"wp:attachment":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=20843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=20843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=20843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}