{"id":20847,"date":"2026-07-14T19:28:53","date_gmt":"2026-07-14T23:28:53","guid":{"rendered":"https:\/\/www.primeranota.cl\/web\/?p=20847"},"modified":"2026-07-14T19:28:53","modified_gmt":"2026-07-14T23:28:53","slug":"224-toneladas-de-basura-retirada-de-la-isla-cautin-en-2-dias-casi-la-mitad-de-lo-que-chao-cachureos-lleva-en-temuco-este-ano","status":"publish","type":"post","link":"https:\/\/www.primeranota.cl\/web\/region\/224-toneladas-de-basura-retirada-de-la-isla-cautin-en-2-dias-casi-la-mitad-de-lo-que-chao-cachureos-lleva-en-temuco-este-ano\/","title":{"rendered":"224 toneladas de basura retirada de la Isla Caut\u00edn en 2 d\u00edas: casi la mitad de lo que Chao Cachureos lleva en Temuco este a\u00f1o"},"content":{"rendered":"<p><strong><em>Colchones, refrigeradores, adem\u00e1s de basura domiciliaria, fueron parte de los desechos con los que se encontraron las cuadrillas de limpieza municipales en un lugar que est\u00e1 a un costado del Parque Isla Caut\u00edn y a metros del lecho del r\u00edo hom\u00f3nimo. <\/em><\/strong><\/p>\n<p><strong>\u00a0<\/strong>En apenas 48 horas fueron retiradas un total de 224 toneladas de desechos desde lo que se hab\u00eda convertido en un aut\u00e9ntico basural en las inmediaciones de la ribera del r\u00edo Caut\u00edn, el equivalente en peso al 43% de las 520 toneladas recogidas por los 34 operativos de \u201cChao Cachureos\u201d que se han hecho en lo que va del a\u00f1o en los barrios.<\/p>\n<p>Este encomiable esfuerzo de los equipos de limpieza de la Direcci\u00f3n de Medio Ambiente, Aseo y Ornato (Dimao) de la Municipalidad de Temuco, no ser\u00eda necesario de no existir inescrupulosos que creen que los terrenos aleda\u00f1os al Parque Isla Caut\u00edn son un basurero donde se pueden desechar incluso colchones o refrigeradores, como los que fueron encontrados durante las operaciones de barrido y retiro. Todo esto, en un lugar que, por si fuera poco, es h\u00e1bitat de aves nativas.<\/p>\n<p>\u201cAqu\u00ed, a orillas de nuestro r\u00edo Caut\u00edn que estamos tratando de recuperar, hemos retirado en solo dos d\u00edas 224 toneladas de desechos, porque hay personas que se sienten con el derecho de venir a tirar su basura. Es un esfuerzo humano, material y econ\u00f3mico que hace la Municipalidad de Temuco para que esto no siga proliferando\u201d comenz\u00f3 se\u00f1alando el alcalde Roberto Neira, quien junto a los concejales Micaela Becker y Esteban Barriga lleg\u00f3 hasta el sitio del microbasural para supervisar las faenas de limpieza.<\/p>\n<p>En esa l\u00ednea el edil record\u00f3 que \u201cel estar aqu\u00ed con nuestros equipos destinados durante dos d\u00edas, obviamente que nos obliga a descuidar otros sectores de Temuco donde tambi\u00e9n son necesarios porque igualmente van a botar basura\u201d, por lo que hizo un llamado a la ciudadan\u00eda a contratar \u00fanicamente servicios de retiro de deshechos y escombros autorizados, de los que exista certeza de que no acaban tirando sus cargas en lugares p\u00fablicos no habilitados, como por ejemplo la ribera del Caut\u00edn.<\/p>\n<p>As\u00ed mismo, el jefe comunal reiter\u00f3 la vigencia de la campa\u00f1a \u201cEcovigilantes\u201d, que invita a las vecinas y vecinos a denunciar a trav\u00e9s de videos y\/o fotograf\u00edas a quienes botan basura en la v\u00eda p\u00fablica o sitios eriazos, enviando dicho material audiovisual al n\u00famero de WhatsApp +56985702749<\/p>\n<p><strong>Labor permanente<\/strong><\/p>\n<p>El director de la Dimao, Miguel \u00c1ngel Acu\u00f1a, explic\u00f3 que los equipos de su direcci\u00f3n deben \u201crealizar peri\u00f3dicamente estos operativos aqu\u00ed porque el acceso a este sector carece de control y, por tanto, siempre habr\u00e1 inescrupulosos que vengan y boten basura. Por eso hemos realizado algunas obras de mitigaci\u00f3n, como la construcci\u00f3n de una zanja que al menos dificulte el que vengan aqu\u00ed a arrojar desechos\u201d, detall\u00f3 el profesional, enfatizando el llamado a la ciudadan\u00eda a no contribuir a la contaminaci\u00f3n de un sitio que debiese ser un refugio natural, y no un vertedero de \u201cbasura domiciliaria, escombros y ramas, que encontramos regularmente\u201d.<\/p>\n<p>Por su parte, la concejala Micaela Becker se\u00f1al\u00f3 que \u201cvoy a hablar por m\u00ed y yo creo que, por todos los concejales, al felicitar a la Dimao y a la administraci\u00f3n municipal por esta iniciativa que busca recuperar nuestro r\u00edo Caut\u00edn. No podemos dejar que ensucien nuestra ciudad, y en ese sentido el llamado es a denunciar a quienes lo hacen\u201d.<\/p>\n<p>Becker destac\u00f3 que en Temuco los recursos p\u00fablicos se est\u00e9n utilizando para limpiar y hermosear lugares clave como la ribera del Caut\u00edn, y \u201clo mismo respecto del centro, donde se est\u00e1 ejecutando un plan para pintar treinta y una fachadas del centro hist\u00f3rico, se est\u00e1n renovando los paraderos, se est\u00e1n cambiando los basureros, se est\u00e1n haciendo esfuerzos, se est\u00e1n utilizando los recursos p\u00fablicos para mejorar nuestra ciudad. El llamado entonces es claro: cuid\u00e9mosla\u201d.<\/p>\n<p>Su colega Esteban Barriga resalt\u00f3 que \u201ceste no es un trabajo puntual, sino algo que ha venido haciendo el municipio, y no con recursos extra, sino con los que tenemos a\u00f1o a a\u00f1o, muestra de ello es que hoy tenemos 70 microbasurales en Temuco, en vez de los m\u00e1s de 230 que hab\u00eda en 2021\u201d. As\u00ed mismo, puso en realce la importancia de \u201ccuidar este lugar, casa de fauna nativa, de aves como el siete colores, garzas, adem\u00e1s de estar cerca de sectores residenciales\u201d.<\/p>\n<p>El llamado de las autoridades no solo apunta a denunciar a los infractores a trav\u00e9s de los canales oficiales dispuestos; el foco tambi\u00e9n apunta a asumir una corresponsabilidad activa como ciudadanos. Muchas de las ofertas que circulan en Facebook y redes sociales para retirar escombros y cachureos a precios econ\u00f3micos terminan, lamentablemente, en las riberas del r\u00edo Caut\u00edn o sitios eriazos. Mientras esto siga ocurriendo, los esfuerzos municipales y recursos p\u00fablicos invertidos ser\u00e1n en vano, convirtiendo la limpieza del entorno en un cuento de nunca acabar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colchones, refrigeradores, adem\u00e1s de basura domiciliaria, fueron parte de los desechos con los que se encontraron las cuadrillas de limpieza municipales en un lugar que&#8230;<\/p>\n","protected":false},"author":2,"featured_media":20848,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","wpai_meta_description":"","footnotes":""},"categories":[267,3],"tags":[],"class_list":["post-20847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","category-region"],"_links":{"self":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/20847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=20847"}],"version-history":[{"count":1,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/20847\/revisions"}],"predecessor-version":[{"id":20849,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/20847\/revisions\/20849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/20848"}],"wp:attachment":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=20847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=20847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=20847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}