{"id":3215,"date":"2018-10-13T09:40:49","date_gmt":"2018-10-13T12:40:49","guid":{"rendered":"http:\/\/www.primeranota.cl\/web\/?p=3215"},"modified":"2018-10-13T09:46:18","modified_gmt":"2018-10-13T12:46:18","slug":"javiera-blanco-renuncia-al-cde-por-incomodidad-de-los-consejeros","status":"publish","type":"post","link":"https:\/\/www.primeranota.cl\/web\/pais\/javiera-blanco-renuncia-al-cde-por-incomodidad-de-los-consejeros\/","title":{"rendered":"Javiera Blanco renuncia al CDE por \u201cincomodidad de los consejeros\u201d"},"content":{"rendered":"<p>La ex ministra de Justicia explic\u00f3 que \u00abla incomodidad de los consejeros, que la entiendo, hace que En entrevista con El Mercurio, la ex secretaria de Estado, cuya presunta responsabilidad en la crisis de la instituci\u00f3n y el desarrollo del programa Ascar est\u00e1 siendo investigada por la Fiscal\u00eda, explic\u00f3 que \u00abla incomodidad de los consejeros, que la entiendo, hace que tome esta decisi\u00f3n\u00bb.tome esta decisi\u00f3n\u00bb.<br \/>\nJaviera Blanco, anunci\u00f3 este s\u00e1bado su renuncia al Consejo de Defensa del Estado, en medio de la presi\u00f3n por su supuesto v\u00ednculo al caso que investiga las irregularidades ocurridas en el Servicio Nacional de Menores (Sename).<br \/>\n\u00abPretender responsabilizar a mi persona por todo ese abandono hist\u00f3rico (de la infancia), de d\u00e9cadas, resulta poco cre\u00edble\u00bb, dijo, junto con asegurar que las personas que fueron contratadas durante su gesti\u00f3n para trabajar en Ascar lo hicieron solo para ese plan y no para otros fines.<br \/>\n\u00abYo solo puedo dar cuenta de mi gesti\u00f3n\u00bb, recalc\u00f3. Lea la entrevista completa en la edici\u00f3n de hoy de El Mercurio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ex ministra de Justicia explic\u00f3 que \u00abla incomodidad de los consejeros, que la entiendo, hace que En entrevista con El Mercurio, la ex secretaria&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","wpai_meta_description":"","footnotes":""},"categories":[4,267],"tags":[],"class_list":["post-3215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pais","category-portada"],"_links":{"self":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/3215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/comments?post=3215"}],"version-history":[{"count":1,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/3215\/revisions"}],"predecessor-version":[{"id":3216,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/posts\/3215\/revisions\/3216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media\/2066"}],"wp:attachment":[{"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/media?parent=3215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/categories?post=3215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primeranota.cl\/web\/wp-json\/wp\/v2\/tags?post=3215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}